{"id":93076,"date":"2011-09-13T10:00:44","date_gmt":"2011-09-13T15:00:44","guid":{"rendered":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg"},"modified":"2011-09-13T10:00:44","modified_gmt":"2011-09-13T15:00:44","slug":"iphone-4-2-2","status":"inherit","type":"attachment","link":"https:\/\/www.applegazette.com\/it\/iphone-4-2-2\/","title":{"rendered":"iphone 4"},"author":44,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_links_to":"","_links_to_target":""},"class_list":["post-93076","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>iphone 4 - Apple Gazette<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"iphone 4 - Apple Gazette\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Apple Gazette\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/applegazette\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.applegazette.com\\\/wp-content\\\/uploads\\\/iphone-4.jpg\",\"url\":\"https:\\\/\\\/www.applegazette.com\\\/wp-content\\\/uploads\\\/iphone-4.jpg\",\"name\":\"iphone 4 - Apple Gazette\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.applegazette.com\\\/#website\"},\"datePublished\":\"2011-09-13T15:00:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.applegazette.com\\\/wp-content\\\/uploads\\\/iphone-4.jpg#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.applegazette.com\\\/wp-content\\\/uploads\\\/iphone-4.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.applegazette.com\\\/wp-content\\\/uploads\\\/iphone-4.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.applegazette.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"iphone 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.applegazette.com\\\/#website\",\"url\":\"https:\\\/\\\/www.applegazette.com\\\/\",\"name\":\"Apple Gazette\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.applegazette.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.applegazette.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.applegazette.com\\\/#organization\",\"name\":\"AppleGazette\",\"url\":\"https:\\\/\\\/www.applegazette.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.applegazette.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.applegazette.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/apple-gazette-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.applegazette.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/apple-gazette-logo.png\",\"width\":1850,\"height\":330,\"caption\":\"AppleGazette\"},\"image\":{\"@id\":\"https:\\\/\\\/www.applegazette.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/applegazette\\\/\",\"https:\\\/\\\/x.com\\\/applegazette\",\"https:\\\/\\\/www.pinterest.com\\\/applegazette\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"iphone 4 - Apple Gazette","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"iphone 4 - Apple Gazette","og_url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg","og_site_name":"Apple Gazette","article_publisher":"https:\/\/www.facebook.com\/applegazette\/","og_image":[{"width":500,"height":388,"url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg","url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg","name":"iphone 4 - Apple Gazette","isPartOf":{"@id":"https:\/\/www.applegazette.com\/#website"},"datePublished":"2011-09-13T15:00:44+00:00","breadcrumb":{"@id":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.applegazette.com\/"},{"@type":"ListItem","position":2,"name":"iphone 4"}]},{"@type":"WebSite","@id":"https:\/\/www.applegazette.com\/#website","url":"https:\/\/www.applegazette.com\/","name":"Apple Gazette","description":"","publisher":{"@id":"https:\/\/www.applegazette.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.applegazette.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.applegazette.com\/#organization","name":"AppleGazette","url":"https:\/\/www.applegazette.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.applegazette.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/2024\/04\/apple-gazette-logo.png","contentUrl":"https:\/\/www.applegazette.com\/wp-content\/uploads\/2024\/04\/apple-gazette-logo.png","width":1850,"height":330,"caption":"AppleGazette"},"image":{"@id":"https:\/\/www.applegazette.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/applegazette\/","https:\/\/x.com\/applegazette","https:\/\/www.pinterest.com\/applegazette\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"232\" src=\"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4-300x232.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4-300x232.jpg 300w, https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"500","height":"388","hwstring_small":"height='96' width='123'","file":"iphone-4.jpg","sizes":{"thumbnail":{"file":"iphone-4-140x140.jpg","width":"140","height":"140","source_url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4-140x140.jpg"},"medium":{"file":"iphone-4-300x232.jpg","width":"300","height":"232","source_url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4-300x232.jpg"},"boombox_image360x270":{"file":"iphone-4-360x270.jpg","width":360,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4-360x270.jpg"},"large":{"file":"iphone-4-500x388.jpg","width":500,"height":388,"mime_type":"image\/jpeg","source_url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4-500x388.jpg"},"boombox_image768":{"file":"iphone-4-500x388.jpg","width":500,"height":388,"mime_type":"image\/jpeg","source_url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4-500x388.jpg"},"full":{"file":"iphone-4.jpg","width":500,"height":388,"mime_type":"image\/jpeg","source_url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":null,"source_url":"https:\/\/www.applegazette.com\/wp-content\/uploads\/iphone-4.jpg","filename":"iphone-4.jpg","filesize":73215,"_links":{"self":[{"href":"https:\/\/www.applegazette.com\/it\/wp-json\/wp\/v2\/media\/93076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.applegazette.com\/it\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.applegazette.com\/it\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.applegazette.com\/it\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.applegazette.com\/it\/wp-json\/wp\/v2\/comments?post=93076"}]}}